{"id":19,"date":"2026-04-14T14:39:20","date_gmt":"2026-04-14T14:39:20","guid":{"rendered":"https:\/\/www.contaminazionifest.it\/web\/?page_id=19"},"modified":"2026-04-23T11:15:38","modified_gmt":"2026-04-23T09:15:38","slug":"ticket","status":"publish","type":"page","link":"https:\/\/www.contaminazionifest.it\/web\/ticket\/","title":{"rendered":"Ticket"},"content":{"rendered":"        <form class=\"cfest-form\" data-form-type=\"pubblico\" novalidate>\n            <div class=\"cfest-form-row\">\n                <div class=\"cfest-form-field\">\n                    <label for=\"cfest-p-first\">Nome *<\/label>\n                    <input id=\"cfest-p-first\" name=\"first_name\" type=\"text\" required maxlength=\"100\">\n                <\/div>\n                <div class=\"cfest-form-field\">\n                    <label for=\"cfest-p-last\">Cognome *<\/label>\n                    <input id=\"cfest-p-last\" name=\"last_name\" type=\"text\" required maxlength=\"100\">\n                <\/div>\n            <\/div>\n\n            <div class=\"cfest-form-row\">\n                <div class=\"cfest-form-field\">\n                    <label for=\"cfest-p-phone\">Numero WhatsApp *<\/label>\n                    <input id=\"cfest-p-phone\" name=\"phone\" type=\"tel\" required maxlength=\"20\">\n                <\/div>\n                <div class=\"cfest-form-field\">\n                    <label for=\"cfest-p-email\">Email *<\/label>\n                    <input id=\"cfest-p-email\" name=\"email\" type=\"email\" required maxlength=\"190\">\n                <\/div>\n            <\/div>\n\n            <div class=\"cfest-form-field\" style=\"max-width:180px\">\n                <label for=\"cfest-p-qty\">Numero biglietti<\/label>\n                <input id=\"cfest-p-qty\" name=\"quantity\" type=\"number\" min=\"1\" max=\"20\" value=\"1\">\n            <\/div>\n\n            <div class=\"cfest-holders\"\n                 data-free=\"0\"\n                 data-label-singular=\"Intestatario biglietto\"\n                 data-label-first=\"Nome\"\n                 data-label-last=\"Cognome\"><\/div>\n\n            <div class=\"cfest-form-total\">\n                <span>Totale<\/span>\n                <strong class=\"cfest-total-amount\" data-price=\"25\">\n                    <span class=\"woocommerce-Price-amount amount\">25,00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span>                <\/strong>\n            <\/div>\n\n            <input type=\"hidden\" name=\"_nonce\" value=\"0f979bf514\">\n            <input type=\"hidden\" name=\"form_type\" value=\"pubblico\">\n\n            <button type=\"submit\" class=\"cfest-submit-btn\">\n                Procedi al pagamento \u2192            <\/button>\n\n            <div class=\"cfest-form-msg\" role=\"alert\" aria-live=\"polite\"><\/div>\n        <\/form>\n        \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":2,"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":196,"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/pages\/19\/revisions\/196"}],"wp:attachment":[{"href":"https:\/\/www.contaminazionifest.it\/web\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}